{"id":6308,"date":"2017-01-13T16:30:52","date_gmt":"2017-01-13T21:30:52","guid":{"rendered":"http:\/\/teamsters.ca\/?p=6308"},"modified":"2019-06-27T20:38:50","modified_gmt":"2019-06-27T20:38:50","slug":"les-gardiens-de-vehicules-blindes-doivent-etre-proteges","status":"publish","type":"post","link":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/","title":{"rendered":"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s"},"content":{"rendered":"<p>Lorsque les enjeux qui minent l&rsquo;industrie des v\u00e9hicules blind\u00e9s sont discut\u00e9s en public, je demanderais \u00e0 tous et \u00e0 toutes de respecter les secrets du m\u00e9tier afin d\u2019assurer la s\u00e9curit\u00e9 des travailleuses et des travailleurs. Trop de renseignements sensibles sur la s\u00e9curit\u00e9 des gardiens de v\u00e9hicules blind\u00e9s circulent en ce moment sur Internet et dans les m\u00e9dias.<\/p>\n<p>J\u2019en ai assez de voir certaines organisations divulguer les secrets du m\u00e9tier et dire, en m\u00eame temps, qu\u2019ils se soucient de la s\u00e9curit\u00e9 des travailleurs. Ces organisations font de la politique sur le dos de ceux et celles qui oeuvrent dans cette industrie. C\u2019est \u00e0 la fois dangereux et inacceptable.<\/p>\n<p>Travailler dans le monde des v\u00e9hicules blind\u00e9s n&rsquo;est jamais sans risques et les conditions ne seront jamais parfaitement s\u00e9curitaires. Plut\u00f4t que d\u2019en parler publiquement, il faut s&rsquo;attaquer aux probl\u00e8mes de mani\u00e8re sens\u00e9e. De fait, le syndicat des Teamsters est toujours \u00e0 l&rsquo;\u00e9coute de ses membres et prend les refus de travailler tr\u00e8s au s\u00e9rieux. C&rsquo;est justement \u00e0 cause des conversations que j&rsquo;ai eues avec des membres que j&rsquo;\u00e9cris ce billet.<\/p>\n<p>Les Teamsters m\u00e8nent une lutte intelligente en prenant soin de ne mettre personne en danger. C\u2019est le seul moyen efficace de prot\u00e9ger les travailleurs de l\u2019industrie et de faire entendre nos revendications par les d\u00e9cideurs politiques \u00e0 Ottawa.<\/p>\n<p>La vie des travailleurs n\u2019a pas de prix, ne l\u2019oublions jamais.<\/p>\n<p><em>Par Jason Sweet, directeur de la Division des v\u00e9hicules blind\u00e9s de Teamsters Canada<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque les enjeux qui minent l&rsquo;industrie des v\u00e9hicules blind\u00e9s sont discut\u00e9s en public, je demanderais \u00e0 tous et \u00e0 toutes de respecter les secrets du m\u00e9tier afin d\u2019assurer la s\u00e9curit\u00e9 des travailleuses et des travailleurs. Trop de renseignements sensibles sur la s\u00e9curit\u00e9 des gardiens de v\u00e9hicules blind\u00e9s circulent en ce moment sur Internet et dans [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":6305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[1138,1140,1114,1137],"tags":[],"class_list":{"0":"post-6308","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-alberta-fr","8":"category-canada-region-fr","9":"category-nouvelles","10":"category-region-fr"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.5 (Yoast SEO v25.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s | Teamsters Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Lorsque les enjeux qui minent l&rsquo;industrie des v\u00e9hicules blind\u00e9s sont discut\u00e9s en public, je demanderais \u00e0 tous et \u00e0 toutes de respecter les secrets du m\u00e9tier afin d\u2019assurer la s\u00e9curit\u00e9 des travailleuses et des travailleurs. Trop de renseignements sensibles sur la s\u00e9curit\u00e9 des gardiens de v\u00e9hicules blind\u00e9s circulent en ce moment sur Internet et dans [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/\" \/>\n<meta property=\"og:site_name\" content=\"Teamsters Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Teamsterscanada\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-13T21:30:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-27T20:38:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1166\" \/>\n\t<meta property=\"og:image:height\" content=\"656\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"St\u00e9phanie Meunier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TeamstersCanada\" \/>\n<meta name=\"twitter:site\" content=\"@TeamstersCanada\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"St\u00e9phanie Meunier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/\"},\"author\":{\"name\":\"St\u00e9phanie Meunier\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/3e6ffefc39fe2f212400b7d8d0a4a0c1\"},\"headline\":\"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s\",\"datePublished\":\"2017-01-13T21:30:52+00:00\",\"dateModified\":\"2019-06-27T20:38:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/\"},\"wordCount\":282,\"publisher\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg\",\"articleSection\":[\"Alberta\",\"Canada\",\"Nouvelles\",\"R\u00e9gion\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/\",\"url\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/\",\"name\":\"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s | Teamsters Canada\",\"isPartOf\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg\",\"datePublished\":\"2017-01-13T21:30:52+00:00\",\"dateModified\":\"2019-06-27T20:38:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#primaryimage\",\"url\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg\",\"contentUrl\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg\",\"width\":1166,\"height\":656},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/teamsters.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#website\",\"url\":\"https:\/\/teamsters.ca\/fr\/\",\"name\":\"Teamsters Canada\",\"description\":\"A Canadian union representing over 125 000 members\",\"publisher\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teamsters.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#organization\",\"name\":\"Teamsters Canada\",\"url\":\"https:\/\/teamsters.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2019\/08\/TeamstersCanada.png\",\"contentUrl\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2019\/08\/TeamstersCanada.png\",\"width\":545,\"height\":181,\"caption\":\"Teamsters Canada\"},\"image\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Teamsterscanada\/\",\"https:\/\/x.com\/TeamstersCanada\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/3e6ffefc39fe2f212400b7d8d0a4a0c1\",\"name\":\"St\u00e9phanie Meunier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e4e8404e91ed71cb473fa2708849669810cf083c89825a3d2dd0d47dd6b2be77?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e4e8404e91ed71cb473fa2708849669810cf083c89825a3d2dd0d47dd6b2be77?s=96&d=mm&r=g\",\"caption\":\"St\u00e9phanie Meunier\"},\"url\":\"https:\/\/teamsters.ca\/fr\/author\/smeunier\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s | Teamsters Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/","og_locale":"fr_CA","og_type":"article","og_title":"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s","og_description":"Lorsque les enjeux qui minent l&rsquo;industrie des v\u00e9hicules blind\u00e9s sont discut\u00e9s en public, je demanderais \u00e0 tous et \u00e0 toutes de respecter les secrets du m\u00e9tier afin d\u2019assurer la s\u00e9curit\u00e9 des travailleuses et des travailleurs. Trop de renseignements sensibles sur la s\u00e9curit\u00e9 des gardiens de v\u00e9hicules blind\u00e9s circulent en ce moment sur Internet et dans [&hellip;]","og_url":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/","og_site_name":"Teamsters Canada","article_publisher":"https:\/\/www.facebook.com\/Teamsterscanada\/","article_published_time":"2017-01-13T21:30:52+00:00","article_modified_time":"2019-06-27T20:38:50+00:00","og_image":[{"width":1166,"height":656,"url":"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg","type":"image\/jpeg"}],"author":"St\u00e9phanie Meunier","twitter_card":"summary_large_image","twitter_creator":"@TeamstersCanada","twitter_site":"@TeamstersCanada","twitter_misc":{"\u00c9crit par":"St\u00e9phanie Meunier","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#article","isPartOf":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/"},"author":{"name":"St\u00e9phanie Meunier","@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/3e6ffefc39fe2f212400b7d8d0a4a0c1"},"headline":"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s","datePublished":"2017-01-13T21:30:52+00:00","dateModified":"2019-06-27T20:38:50+00:00","mainEntityOfPage":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/"},"wordCount":282,"publisher":{"@id":"https:\/\/teamsters.ca\/fr\/#organization"},"image":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#primaryimage"},"thumbnailUrl":"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg","articleSection":["Alberta","Canada","Nouvelles","R\u00e9gion"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/","url":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/","name":"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s | Teamsters Canada","isPartOf":{"@id":"https:\/\/teamsters.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#primaryimage"},"image":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#primaryimage"},"thumbnailUrl":"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg","datePublished":"2017-01-13T21:30:52+00:00","dateModified":"2019-06-27T20:38:50+00:00","breadcrumb":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#primaryimage","url":"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg","contentUrl":"https:\/\/teamsters.ca\/wp-content\/uploads\/2017\/01\/armouredcarbrinks.jpg","width":1166,"height":656},{"@type":"BreadcrumbList","@id":"https:\/\/teamsters.ca\/fr\/blog\/2017\/01\/13\/les-gardiens-de-vehicules-blindes-doivent-etre-proteges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teamsters.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Les gardiens de v\u00e9hicules blind\u00e9s doivent \u00eatre prot\u00e9g\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/teamsters.ca\/fr\/#website","url":"https:\/\/teamsters.ca\/fr\/","name":"Teamsters Canada","description":"A Canadian union representing over 125 000 members","publisher":{"@id":"https:\/\/teamsters.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teamsters.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/teamsters.ca\/fr\/#organization","name":"Teamsters Canada","url":"https:\/\/teamsters.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/teamsters.ca\/wp-content\/uploads\/2019\/08\/TeamstersCanada.png","contentUrl":"https:\/\/teamsters.ca\/wp-content\/uploads\/2019\/08\/TeamstersCanada.png","width":545,"height":181,"caption":"Teamsters Canada"},"image":{"@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Teamsterscanada\/","https:\/\/x.com\/TeamstersCanada"]},{"@type":"Person","@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/3e6ffefc39fe2f212400b7d8d0a4a0c1","name":"St\u00e9phanie Meunier","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e4e8404e91ed71cb473fa2708849669810cf083c89825a3d2dd0d47dd6b2be77?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4e8404e91ed71cb473fa2708849669810cf083c89825a3d2dd0d47dd6b2be77?s=96&d=mm&r=g","caption":"St\u00e9phanie Meunier"},"url":"https:\/\/teamsters.ca\/fr\/author\/smeunier\/"}]}},"_links":{"self":[{"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/posts\/6308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/comments?post=6308"}],"version-history":[{"count":1,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/posts\/6308\/revisions"}],"predecessor-version":[{"id":10092,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/posts\/6308\/revisions\/10092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/media\/6305"}],"wp:attachment":[{"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/media?parent=6308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/categories?post=6308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/tags?post=6308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}