{"id":6232,"date":"2016-11-30T08:35:43","date_gmt":"2016-11-30T13:35:43","guid":{"rendered":"http:\/\/teamsters.ca\/?p=6232"},"modified":"2019-06-27T20:38:51","modified_gmt":"2019-06-27T20:38:51","slug":"les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge","status":"publish","type":"post","link":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/","title":{"rendered":"Les Teamsters saluent le projet de remplacement de la ligne 3 d&rsquo;Enbridge"},"content":{"rendered":"<p>Ottawa, 29 novembre 2016 \u2014 Le syndicat des Teamsters salue la d\u00e9cision du gouvernement f\u00e9d\u00e9ral d\u2019approuver le remplacement de la ligne 3 d\u2019Enbridge, un projet d\u2019ol\u00e9oduc ambitieux qui aidera des milliers de travailleurs et leurs familles.<\/p>\n<p>Le m\u00e9gaprojet de 7,5 G$ entrainera des retomb\u00e9es de 514 millions de dollars en taxes et imp\u00f4ts pour les gouvernements provinciaux et f\u00e9d\u00e9ral et ajoutera 3 G$ au PIB du Canada. Les communaut\u00e9s le long du trac\u00e9 de l\u2019ol\u00e9oduc b\u00e9n\u00e9ficieront \u00e9galement de la manne puisque les travailleurs auront besoin de nourriture, d\u2019h\u00e9bergement et de plusieurs autres produits et services.<\/p>\n<p>\u00ab Quand les temps sont difficiles, on doit aussi regarder au-del\u00e0 des impacts \u00e9conomiques, explique le pr\u00e9sident de Teamsters Canada, Fran\u00e7ois Laporte. Nous y voyons l\u2019espoir que des milliers de Canadiens touch\u00e9s par la chute des prix du p\u00e9trole puissent enfin am\u00e9liorer leur sort. \u00bb<\/p>\n<p>En effet, le remplacement de la ligne 3 d\u2019Enbridge cr\u00e9era des milliers de bons emplois qui viendront de pair avec des r\u00e9gimes de retraite, des avantages sociaux et des bon salaires. M\u00eame si les emplois dans le secteur de la construction ne sont pas permanents, ces salaires permettront aux travailleurs de faire une mise de fonds sur leur premi\u00e8re maison, d\u2019envoyer leurs enfants \u00e0 l\u2019universit\u00e9 ou de tenir le coup jusqu\u2019au prochain gros projet de construction.<\/p>\n<p>\u00ab Ce projet cr\u00e9ateur d\u2019emplois est tr\u00e8s utile en cette \u00e8re o\u00f9 les in\u00e9galit\u00e9s sont de plus en plus pr\u00e9sentes, o\u00f9 les salaires stagnent et o\u00f9 la classe moyenne perd du terrain, ajoute le leader syndical. \u00bb<\/p>\n<p>Au-del\u00e0 des bienfaits \u00e9conomiques, le projet de la ligne 3 se veut d\u2019abord une op\u00e9ration d\u2019entretien puisque l\u2019ol\u00e9oduc original a \u00e9t\u00e9 mis en service en 1968. Tous les tron\u00e7ons de la ligne seront remplac\u00e9s par des tuyaux en acier et les toutes derni\u00e8res technologies de rev\u00eatement seront mises en place. Par cons\u00e9quent, les anciens tuyaux seront retir\u00e9s.<\/p>\n<p>Les Teamsters croient que tous les Canadiens et Canadiennes en tireront profit, puisqu\u2019un ol\u00e9oduc moderne, s\u00e9curitaire et entretenu r\u00e9guli\u00e8rement est d\u2019une importance capitale pour tous et toutes.<\/p>\n<p><em>Les Teamsters repr\u00e9sentent les int\u00e9r\u00eats de 115 000 membres au Canada dans tous les secteurs d\u2019activit\u00e9. La Fraternit\u00e9 internationale des Teamsters, \u00e0 laquelle Teamsters Canada est affili\u00e9, compte 1,4 million de membres en Am\u00e9rique du Nord.<\/em><\/p>\n<p style=\"text-align: center;\">-30-<\/p>\n<p>Renseignements :<\/p>\n<p>St\u00e9phane Lacroix, directeur des relations publiques<br \/>\nCell : 514 609-5101<br \/>\n<a href=\"mailto:slacroix@teamsters.ca\">slacroix@teamsters.ca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le syndicat des Teamsters salue la d\u00e9cision du gouvernement f\u00e9d\u00e9ral d\u2019approuver le remplacement de la ligne 3 d\u2019Enbridge, un projet d\u2019ol\u00e9oduc ambitieux qui aidera des milliers de travailleurs et leurs familles. Le m\u00e9gaprojet de 7,5 G$ entrainera des retomb\u00e9es de 514 millions de dollars en taxes et imp\u00f4ts&#8230;<\/p>\n","protected":false},"author":8,"featured_media":6225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[1140,1141,1114,1146],"tags":[],"class_list":{"0":"post-6232","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canada-region-fr","8":"category-manitoba-fr","9":"category-nouvelles","10":"category-saskatchewan-fr"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.5 (Yoast SEO v25.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les Teamsters saluent le projet de remplacement de la ligne 3 d&#039;Enbridge | Teamsters Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Teamsters saluent le projet de remplacement de la ligne 3 d&#039;Enbridge\" \/>\n<meta property=\"og:description\" content=\"Le syndicat des Teamsters salue la d\u00e9cision du gouvernement f\u00e9d\u00e9ral d\u2019approuver le remplacement de la ligne 3 d\u2019Enbridge, un projet d\u2019ol\u00e9oduc ambitieux qui aidera des milliers de travailleurs et leurs familles. Le m\u00e9gaprojet de 7,5 G$ entrainera des retomb\u00e9es de 514 millions de dollars en taxes et imp\u00f4ts...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/\" \/>\n<meta property=\"og:site_name\" content=\"Teamsters Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Teamsterscanada\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-30T13:35:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-27T20:38:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1166\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"St\u00e9phanie Meunier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TeamstersCanada\" \/>\n<meta name=\"twitter:site\" content=\"@TeamstersCanada\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"St\u00e9phanie Meunier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/\"},\"author\":{\"name\":\"St\u00e9phanie Meunier\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/3e6ffefc39fe2f212400b7d8d0a4a0c1\"},\"headline\":\"Les Teamsters saluent le projet de remplacement de la ligne 3 d&rsquo;Enbridge\",\"datePublished\":\"2016-11-30T13:35:43+00:00\",\"dateModified\":\"2019-06-27T20:38:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/\"},\"wordCount\":441,\"publisher\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg\",\"articleSection\":[\"Canada\",\"Manitoba\",\"Nouvelles\",\"Saskatchewan\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/\",\"url\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/\",\"name\":\"Les Teamsters saluent le projet de remplacement de la ligne 3 d'Enbridge | Teamsters Canada\",\"isPartOf\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg\",\"datePublished\":\"2016-11-30T13:35:43+00:00\",\"dateModified\":\"2019-06-27T20:38:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#primaryimage\",\"url\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg\",\"contentUrl\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg\",\"width\":1166,\"height\":708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/teamsters.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Teamsters saluent le projet de remplacement de la ligne 3 d&#8217;Enbridge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#website\",\"url\":\"https:\/\/teamsters.ca\/fr\/\",\"name\":\"Teamsters Canada\",\"description\":\"A Canadian union representing over 125 000 members\",\"publisher\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teamsters.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#organization\",\"name\":\"Teamsters Canada\",\"url\":\"https:\/\/teamsters.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2019\/08\/TeamstersCanada.png\",\"contentUrl\":\"https:\/\/teamsters.ca\/wp-content\/uploads\/2019\/08\/TeamstersCanada.png\",\"width\":545,\"height\":181,\"caption\":\"Teamsters Canada\"},\"image\":{\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Teamsterscanada\/\",\"https:\/\/x.com\/TeamstersCanada\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/3e6ffefc39fe2f212400b7d8d0a4a0c1\",\"name\":\"St\u00e9phanie Meunier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e4e8404e91ed71cb473fa2708849669810cf083c89825a3d2dd0d47dd6b2be77?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e4e8404e91ed71cb473fa2708849669810cf083c89825a3d2dd0d47dd6b2be77?s=96&d=mm&r=g\",\"caption\":\"St\u00e9phanie Meunier\"},\"url\":\"https:\/\/teamsters.ca\/fr\/author\/smeunier\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Teamsters saluent le projet de remplacement de la ligne 3 d'Enbridge | Teamsters Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/","og_locale":"fr_CA","og_type":"article","og_title":"Les Teamsters saluent le projet de remplacement de la ligne 3 d'Enbridge","og_description":"Le syndicat des Teamsters salue la d\u00e9cision du gouvernement f\u00e9d\u00e9ral d\u2019approuver le remplacement de la ligne 3 d\u2019Enbridge, un projet d\u2019ol\u00e9oduc ambitieux qui aidera des milliers de travailleurs et leurs familles. Le m\u00e9gaprojet de 7,5 G$ entrainera des retomb\u00e9es de 514 millions de dollars en taxes et imp\u00f4ts...","og_url":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/","og_site_name":"Teamsters Canada","article_publisher":"https:\/\/www.facebook.com\/Teamsterscanada\/","article_published_time":"2016-11-30T13:35:43+00:00","article_modified_time":"2019-06-27T20:38:51+00:00","og_image":[{"width":1166,"height":708,"url":"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg","type":"image\/jpeg"}],"author":"St\u00e9phanie Meunier","twitter_card":"summary_large_image","twitter_creator":"@TeamstersCanada","twitter_site":"@TeamstersCanada","twitter_misc":{"\u00c9crit par":"St\u00e9phanie Meunier","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#article","isPartOf":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/"},"author":{"name":"St\u00e9phanie Meunier","@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/3e6ffefc39fe2f212400b7d8d0a4a0c1"},"headline":"Les Teamsters saluent le projet de remplacement de la ligne 3 d&rsquo;Enbridge","datePublished":"2016-11-30T13:35:43+00:00","dateModified":"2019-06-27T20:38:51+00:00","mainEntityOfPage":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/"},"wordCount":441,"publisher":{"@id":"https:\/\/teamsters.ca\/fr\/#organization"},"image":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#primaryimage"},"thumbnailUrl":"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg","articleSection":["Canada","Manitoba","Nouvelles","Saskatchewan"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/","url":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/","name":"Les Teamsters saluent le projet de remplacement de la ligne 3 d'Enbridge | Teamsters Canada","isPartOf":{"@id":"https:\/\/teamsters.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#primaryimage"},"image":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#primaryimage"},"thumbnailUrl":"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg","datePublished":"2016-11-30T13:35:43+00:00","dateModified":"2019-06-27T20:38:51+00:00","breadcrumb":{"@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#primaryimage","url":"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg","contentUrl":"https:\/\/teamsters.ca\/wp-content\/uploads\/2016\/11\/teamster-truck-pipeline.jpg","width":1166,"height":708},{"@type":"BreadcrumbList","@id":"https:\/\/teamsters.ca\/fr\/blog\/2016\/11\/30\/les-teamsters-saluent-le-projet-de-remplacement-de-la-ligne-3-denbridge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teamsters.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Les Teamsters saluent le projet de remplacement de la ligne 3 d&#8217;Enbridge"}]},{"@type":"WebSite","@id":"https:\/\/teamsters.ca\/fr\/#website","url":"https:\/\/teamsters.ca\/fr\/","name":"Teamsters Canada","description":"A Canadian union representing over 125 000 members","publisher":{"@id":"https:\/\/teamsters.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teamsters.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/teamsters.ca\/fr\/#organization","name":"Teamsters Canada","url":"https:\/\/teamsters.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/teamsters.ca\/wp-content\/uploads\/2019\/08\/TeamstersCanada.png","contentUrl":"https:\/\/teamsters.ca\/wp-content\/uploads\/2019\/08\/TeamstersCanada.png","width":545,"height":181,"caption":"Teamsters Canada"},"image":{"@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Teamsterscanada\/","https:\/\/x.com\/TeamstersCanada"]},{"@type":"Person","@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/3e6ffefc39fe2f212400b7d8d0a4a0c1","name":"St\u00e9phanie Meunier","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/teamsters.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e4e8404e91ed71cb473fa2708849669810cf083c89825a3d2dd0d47dd6b2be77?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4e8404e91ed71cb473fa2708849669810cf083c89825a3d2dd0d47dd6b2be77?s=96&d=mm&r=g","caption":"St\u00e9phanie Meunier"},"url":"https:\/\/teamsters.ca\/fr\/author\/smeunier\/"}]}},"_links":{"self":[{"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/posts\/6232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/comments?post=6232"}],"version-history":[{"count":1,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/posts\/6232\/revisions"}],"predecessor-version":[{"id":10103,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/posts\/6232\/revisions\/10103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/media\/6225"}],"wp:attachment":[{"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/media?parent=6232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/categories?post=6232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teamsters.ca\/fr\/wp-json\/wp\/v2\/tags?post=6232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}